{"id":32268,"date":"2022-09-12T02:00:14","date_gmt":"2022-09-12T06:00:14","guid":{"rendered":"https:\/\/fgmtl.org\/?p=32268"},"modified":"2022-10-06T09:49:00","modified_gmt":"2022-10-06T13:49:00","slug":"la-reconciliation-par-une-approche-degal-a-egal","status":"publish","type":"post","link":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/","title":{"rendered":"La r\u00e9conciliation par une approche d&rsquo;\u00e9gal \u00e0 \u00e9gal"},"content":{"rendered":"<h4>Le mot de la FGM, septembre 2022<\/h4>\n<p>Le 30 septembre se tiendra la seconde Journ\u00e9e nationale de la v\u00e9rit\u00e9 et de la r\u00e9conciliation. Le gouvernement du Canada a en effet instaur\u00e9 cette journ\u00e9e de comm\u00e9moration l&rsquo;an dernier. Ce sera l\u2019occasion de r\u00e9fl\u00e9chir aux cons\u00e9quences historiques de la colonisation du territoire que nous habitons, d&rsquo;abord. Mais aussi \u00e0 l\u2019\u00e9tat actuel et \u00e0 l\u2019avenir des relations entre communaut\u00e9s autochtones et allochtones. Il y a encore fort \u00e0 faire pour que la r\u00e9conciliation d\u00e9passe le stade des symboles et des v\u0153ux pieux.<\/p>\n<p>\u00c0 la Fondation du Grand Montr\u00e9al, nous continuons \u00e0 d\u00e9velopper notre contribution \u00e0 cette r\u00e9conciliation. Afin de joindre les gestes \u00e0 la parole (voir notre \u00e9nonc\u00e9 de <a href=\"https:\/\/fgmtl.org\/copieprod\/a-propos\/qui-sommes-nous\/\">reconnaissance territoriale<\/a>), nous avons cr\u00e9\u00e9 l\u2019an dernier le Fonds de soutien aux initiatives autochtones. Dot\u00e9 d\u2019un capital de d\u00e9part de 200 000$, il nous a permis de soutenir dix organismes autochtones du Grand Montr\u00e9al. Certains sont issus, par exemple, de la nation Kanien\u2019keha:ka, gardienne de notre territoire. Nous avons identifi\u00e9 ces organismes \u00e0 travers le prisme de la <a href=\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/philanthropie-basee-sur-la-confiance-la-fgm-cree-le-fonds-collectif-pour-lequite-sociale\/\">philanthropie bas\u00e9e sur la confiance<\/a>. Cette approche novatrice implique l\u2019\u00e9tablissement d\u2019un dialogue d\u2019\u00e9gal \u00e0 \u00e9gal entre donataires et donateurs. Il permet aussi aux communaut\u00e9s cibl\u00e9es d\u2019identifier elles-m\u00eames leurs besoins et les meilleurs outils pour y r\u00e9pondre.<\/p>\n<h5>Apprendre pour mieux comprendre<\/h5>\n<p>Nous avons \u00e9galement r\u00e9solu, dans l\u2019esprit du nouveau <a href=\"https:\/\/fgmtl.org\/copieprod\/a-propos\/qui-sommes-nous\/la-fgm-et-les-objectifs-de-developpement-durable\/\">Plan strat\u00e9gique<\/a> de la Fondation et de son engagement renouvel\u00e9 envers la justice, l\u2019\u00e9quit\u00e9, la diversit\u00e9 et l\u2019inclusion, de former les membres de notre \u00e9quipe pour d\u00e9velopper notre compr\u00e9hension des enjeux historiques et actuels v\u00e9cus par les peuples autochtones. Cette d\u00e9marche nous permet d\u2019agir de mani\u00e8re plus sensible et efficace dans le cadre de notre travail. Elle nous permet aussi de devenir de meilleur\u00b7e\u00b7s citoyen\u00b7ne\u00b7s et de meilleur\u00b7e\u00b7s alli\u00e9\u00b7e\u00b7s. Poursuivez votre lecture pour en savoir plus.<\/p>\n<p>Le don, le partage et la solidarit\u00e9 sont au c\u0153ur des cultures et des pratiques mill\u00e9naires des Autochtones. \u00c0 un moment o\u00f9 les institutions philanthropiques sont elles aussi appel\u00e9es \u00e0 \u00e9voluer et \u00e0 se d\u00e9coloniser, nous devons nous inspirer des savoirs traditionnels des Premiers Peuples. Gardons toujours \u00e0 l\u2019esprit que les individus, les communaut\u00e9s et l\u2019environnement sont profond\u00e9ment interreli\u00e9s. Pour le b\u00e9n\u00e9fice des sept prochaines g\u00e9n\u00e9rations et des suivantes, nous avons le devoir de prendre soin les uns des autres, de pr\u00e9server nos ressources et de prot\u00e9ger l\u2019int\u00e9grit\u00e9 de notre territoire. Cette philosophie correspond pleinement \u00e0 la vision et \u00e0 la mission des fondations communautaires comme la FGM. C\u2019est pourquoi nous r\u00e9it\u00e9rons notre engagement \u00e0 la mettre en \u0153uvre, \u00e0 notre \u00e9chelle, pour aujourd\u2019hui mais surtout pour demain.<\/p>\n<h5>Karel Mayrand<br \/>\nPr\u00e9sident-directeur g\u00e9n\u00e9ral<br \/>\nFondation du Grand Montr\u00e9al<\/h5>\n<div class=\"su-spacer\" style=\"height:20px\"><\/div>\n\n     <\/div> \n    <\/div> \n    <div class=\"sc-wrapper-dark spacing clear\">    \n        <div class=\"wrapper wrap-content\">\n            <div class=\"wrap-770 clear\">\n                \n<h3>Les histoires de la FGM \u00e0 lire ce mois-ci<\/h3>\n<h4><em>Septembre 2022<\/em><\/h4>\n[scNewWrapperTrio ]\n[scSubBlockTrio bgimg=\"\/wp-content\/uploads\/2021\/01\/FGM_WEB_Contribuer.jpg\"]\n<h4>Le Fonds de soutien aux initiatives autochtones<\/h4>\n<p>En reconnaissance des enjeux particuliers v\u00e9cus par les communaut\u00e9s autochtones vivant sur le territoire du Grand Montr\u00e9al, et soucieuse de contribuer financi\u00e8rement \u00e0 leur r\u00e9solution, la FGM a mis sur pied le Fonds de soutien aux initiatives autochtones.<\/p>\n<p><span class=\"cta full red cta-page\"><a href=\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/repenser-la-philanthropie-chez-les-communautes-racisees\/\" target=\"_blank\" rel=\"noopener\">Lire la suite<\/a><\/span><\/p>\n[\/scSubBlockTrio]\n[scSubBlockTrio bgimg=\"\/wp-content\/uploads\/2022\/08\/photo-mikana-pour-site-web.png\"]\n<h4>Mikana<\/h4>\n<p>Mikana, qui signifie\u00a0chemin en langue Anishinabe, est un organisme autochtone sans but lucratif qui a pour mission d\u2019\u0153uvrer au changement social en sensibilisant diff\u00e9rents publics sur les r\u00e9alit\u00e9s et perspectives des peuples autochtones.<\/p>\n<p><span class=\"cta full red cta-page\"><a href=\"https:\/\/fgmtl.org\/copieprod\/notre-impact\/histoires-inspirantes\/mikana\/\" target=\"_blank\" rel=\"noopener\">Lire la suite<\/a><\/span><\/p>\n[\/scSubBlockTrio]\n[scSubBlockTrio bgimg=\"\/wp-content\/uploads\/2022\/08\/Kiuna-2.jpeg\"]\n<h4>Institution Kiuna<\/h4>\n<p>L\u2019Institution Kiuna est un coll\u00e8ge con\u00e7u express\u00e9ment par et pour les \u00e9tudiant\u00b7e\u00b7s autochtones. Elle leur offre un cadre d\u2019enseignement et un milieu de vie qui tiennent compte de leurs particularit\u00e9s culturelles, de leur contexte social et de leurs int\u00e9r\u00eats.<\/p>\n<p><span class=\"cta full red cta-page\"><a href=\"https:\/\/fgmtl.org\/copieprod\/notre-impact\/histoires-inspirantes\/kiuna\/\" rel=\"noopener\">Lire la suite<\/a><\/span><\/p>\n[\/scSubBlockTrio]\n[\/scNewWrapperTrio]\n\n            <\/div> \n        <\/div> \n    <\/div>\n    <div id=\"content\" class=\"wrapper wrap-content spacing clear\" role=\"main\">    \n        <div class=\"wrap-770 main clear\">\n","protected":false},"excerpt":{"rendered":"<p>Pour le b\u00e9n\u00e9fice des prochaines g\u00e9n\u00e9rations, nous avons le devoir d&rsquo;\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin les uns des autres, de pr\u00e9server nos ressources et de prot\u00e9ger l\u2019int\u00e9grit\u00e9 de notre territoire.<\/p>\n","protected":false},"author":6,"featured_media":30190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,28],"tags":[151],"class_list":["post-32268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-billet-de-blogue","tag-mot-du-pdg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La r\u00e9conciliation par une approche d&#039;\u00e9gal \u00e0 \u00e9gal - FGM<\/title>\n<meta name=\"description\" content=\"Nous avons le devoir d&#039;\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9conciliation par une approche d&#039;\u00e9gal \u00e0 \u00e9gal - FGM\" \/>\n<meta property=\"og:description\" content=\"Nous avons le devoir d&#039;\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation du Grand Montr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fondationdugrandmontreal\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T06:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T13:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fgmadmin4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fgmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@fgmontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fgmadmin4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\"},\"author\":{\"name\":\"fgmadmin4\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/381420237e6ca63c5f0679ccb0b96f9e\"},\"headline\":\"La r\u00e9conciliation par une approche d&rsquo;\u00e9gal \u00e0 \u00e9gal\",\"datePublished\":\"2022-09-12T06:00:14+00:00\",\"dateModified\":\"2022-10-06T13:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#organization\"},\"image\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg\",\"keywords\":[\"Mot du PDG\"],\"articleSection\":[\"Nouvelles\",\"Billet de blogue\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\",\"url\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\",\"name\":\"La r\u00e9conciliation par une approche d'\u00e9gal \u00e0 \u00e9gal - FGM\",\"isPartOf\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg\",\"datePublished\":\"2022-09-12T06:00:14+00:00\",\"dateModified\":\"2022-10-06T13:49:00+00:00\",\"description\":\"Nous avons le devoir d'\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.\",\"breadcrumb\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage\",\"url\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg\",\"contentUrl\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Paysage naturel pour Fonds Collectif pour le climat et la transition \u00e9cologique - Collective Fund for Climate and Ecological Transition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fgmtl.org\/copieprod\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9conciliation par une approche d&rsquo;\u00e9gal \u00e0 \u00e9gal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#website\",\"url\":\"https:\/\/fgmtl.org\/copieprod\/\",\"name\":\"Fondation du Grand Montr\u00e9al\",\"description\":\"La Fondation du Grand Montr\u00e9al, votre fondation\",\"publisher\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fgmtl.org\/copieprod\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#organization\",\"name\":\"Fondation du Grand Montr\u00e9al\",\"url\":\"https:\/\/fgmtl.org\/copieprod\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2023\/01\/FGM_LOGO_fr_COUL_Horiz-JPG-scaled.jpg\",\"contentUrl\":\"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2023\/01\/FGM_LOGO_fr_COUL_Horiz-JPG-scaled.jpg\",\"width\":2560,\"height\":215,\"caption\":\"Fondation du Grand Montr\u00e9al\"},\"image\":{\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fondationdugrandmontreal\/\",\"https:\/\/x.com\/fgmontreal\",\"https:\/\/www.instagram.com\/fgmtl\/\",\"https:\/\/www.linkedin.com\/company\/fondation-grand-montreal\/\",\"https:\/\/www.youtube.com\/channel\/UCtXH4VCpL5wjqwExJ9bxlDw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/381420237e6ca63c5f0679ccb0b96f9e\",\"name\":\"fgmadmin4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be33230242e9eeaa8ea7a067bd8fe5fe64315c726d3fdd64498e17fb58b1c028?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be33230242e9eeaa8ea7a067bd8fe5fe64315c726d3fdd64498e17fb58b1c028?s=96&d=blank&r=g\",\"caption\":\"fgmadmin4\"},\"url\":\"https:\/\/fgmtl.org\/copieprod\/author\/fgmadmin4\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9conciliation par une approche d'\u00e9gal \u00e0 \u00e9gal - FGM","description":"Nous avons le devoir d'\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"La r\u00e9conciliation par une approche d'\u00e9gal \u00e0 \u00e9gal - FGM","og_description":"Nous avons le devoir d'\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.","og_url":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/","og_site_name":"Fondation du Grand Montr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/fondationdugrandmontreal\/","article_published_time":"2022-09-12T06:00:14+00:00","article_modified_time":"2022-10-06T13:49:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg","type":"image\/jpeg"}],"author":"fgmadmin4","twitter_card":"summary_large_image","twitter_creator":"@fgmontreal","twitter_site":"@fgmontreal","twitter_misc":{"\u00c9crit par":"fgmadmin4","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#article","isPartOf":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/"},"author":{"name":"fgmadmin4","@id":"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/381420237e6ca63c5f0679ccb0b96f9e"},"headline":"La r\u00e9conciliation par une approche d&rsquo;\u00e9gal \u00e0 \u00e9gal","datePublished":"2022-09-12T06:00:14+00:00","dateModified":"2022-10-06T13:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/fgmtl.org\/copieprod\/#organization"},"image":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage"},"thumbnailUrl":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg","keywords":["Mot du PDG"],"articleSection":["Nouvelles","Billet de blogue"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/","url":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/","name":"La r\u00e9conciliation par une approche d'\u00e9gal \u00e0 \u00e9gal - FGM","isPartOf":{"@id":"https:\/\/fgmtl.org\/copieprod\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage"},"image":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage"},"thumbnailUrl":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg","datePublished":"2022-09-12T06:00:14+00:00","dateModified":"2022-10-06T13:49:00+00:00","description":"Nous avons le devoir d'\u0153uvrer \u00e0 la r\u00e9conciliation, de prendre soin des autres, de pr\u00e9server nos ressources et de prot\u00e9ger notre territoire.","breadcrumb":{"@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#primaryimage","url":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg","contentUrl":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2021\/12\/AdobeStock_376336836-scaled.jpeg","width":2560,"height":1920,"caption":"Paysage naturel pour Fonds Collectif pour le climat et la transition \u00e9cologique - Collective Fund for Climate and Ecological Transition"},{"@type":"BreadcrumbList","@id":"https:\/\/fgmtl.org\/copieprod\/nouvelles\/billet-de-blogue\/la-reconciliation-par-une-approche-degal-a-egal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fgmtl.org\/copieprod\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9conciliation par une approche d&rsquo;\u00e9gal \u00e0 \u00e9gal"}]},{"@type":"WebSite","@id":"https:\/\/fgmtl.org\/copieprod\/#website","url":"https:\/\/fgmtl.org\/copieprod\/","name":"Fondation du Grand Montr\u00e9al","description":"La Fondation du Grand Montr\u00e9al, votre fondation","publisher":{"@id":"https:\/\/fgmtl.org\/copieprod\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fgmtl.org\/copieprod\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/fgmtl.org\/copieprod\/#organization","name":"Fondation du Grand Montr\u00e9al","url":"https:\/\/fgmtl.org\/copieprod\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/fgmtl.org\/copieprod\/#\/schema\/logo\/image\/","url":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2023\/01\/FGM_LOGO_fr_COUL_Horiz-JPG-scaled.jpg","contentUrl":"https:\/\/fgmtl.org\/copieprod\/wp-content\/uploads\/2023\/01\/FGM_LOGO_fr_COUL_Horiz-JPG-scaled.jpg","width":2560,"height":215,"caption":"Fondation du Grand Montr\u00e9al"},"image":{"@id":"https:\/\/fgmtl.org\/copieprod\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fondationdugrandmontreal\/","https:\/\/x.com\/fgmontreal","https:\/\/www.instagram.com\/fgmtl\/","https:\/\/www.linkedin.com\/company\/fondation-grand-montreal\/","https:\/\/www.youtube.com\/channel\/UCtXH4VCpL5wjqwExJ9bxlDw"]},{"@type":"Person","@id":"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/381420237e6ca63c5f0679ccb0b96f9e","name":"fgmadmin4","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/fgmtl.org\/copieprod\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be33230242e9eeaa8ea7a067bd8fe5fe64315c726d3fdd64498e17fb58b1c028?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be33230242e9eeaa8ea7a067bd8fe5fe64315c726d3fdd64498e17fb58b1c028?s=96&d=blank&r=g","caption":"fgmadmin4"},"url":"https:\/\/fgmtl.org\/copieprod\/author\/fgmadmin4\/"}]}},"lang":"fr","translations":{"fr":32268,"en":32286},"meta_box":{"promote_show":"0","promote_title":"","promote_texte":"","promote_cta":"","promote_link":"","promote_target":"0","promote_image":false},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/posts\/32268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/comments?post=32268"}],"version-history":[{"count":6,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/posts\/32268\/revisions"}],"predecessor-version":[{"id":32469,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/posts\/32268\/revisions\/32469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/media\/30190"}],"wp:attachment":[{"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/media?parent=32268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/categories?post=32268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fgmtl.org\/copieprod\/wp-json\/wp\/v2\/tags?post=32268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}